{"id":4052,"count":2,"description":"","link":"https:\/\/www.nyfifth.com\/blog\/tag\/custom-snapback-hats\/","name":"custom snapback hats","slug":"custom-snapback-hats","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.nyfifth.com\/blog\/wp-json\/wp\/v2\/tags\/4052"}],"collection":[{"href":"https:\/\/www.nyfifth.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.nyfifth.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.nyfifth.com\/blog\/wp-json\/wp\/v2\/posts?tags=4052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}